{"id":9992,"date":"2026-03-04T03:27:44","date_gmt":"2026-03-04T03:27:44","guid":{"rendered":"https:\/\/testedwebsite.us\/realestatee\/agent\/cat-door-installer6242\/"},"modified":"2026-03-04T03:27:44","modified_gmt":"2026-03-04T03:27:44","slug":"cat-door-installer6242","status":"publish","type":"agent","link":"https:\/\/testedwebsite.us\/realestatee\/agent\/cat-door-installer6242\/","title":{"rendered":"cat door installer6242"},"content":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","agent_location":[],"agent_category":[],"class_list":["post-9992","agent","type-agent","status-publish","hentry"],"cmb2":{"_agent_contact_details":{"_agent_attached_user":"","_agent_featured":"","_agent_job":"","_agent_email":"jeanettzerangue22@seti.juxal.org","_agent_website":"","_agent_phone":"","_agent_fax":""},"_agent_socials":{"_agent_socials":""},"_agent_location":{"_agent_address":"","_agent_map_location":""}},"_links":{"self":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent\/9992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent"}],"about":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/types\/agent"}],"replies":[{"embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/comments?post=9992"}],"wp:attachment":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/media?parent=9992"}],"wp:term":[{"taxonomy":"agent_location","embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent_location?post=9992"},{"taxonomy":"agent_category","embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent_category?post=9992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}