{"id":4092,"date":"2025-06-21T01:04:30","date_gmt":"2025-06-21T01:04:30","guid":{"rendered":"https:\/\/testedwebsite.us\/realestatee\/agent\/experienced-door-installers7893\/"},"modified":"2025-06-21T01:04:30","modified_gmt":"2025-06-21T01:04:30","slug":"experienced-door-installers7893","status":"publish","type":"agent","link":"https:\/\/testedwebsite.us\/realestatee\/agent\/experienced-door-installers7893\/","title":{"rendered":"experienced door installers7893"},"content":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","agent_location":[],"agent_category":[],"class_list":["post-4092","agent","type-agent","status-publish","hentry"],"cmb2":{"_agent_contact_details":{"_agent_attached_user":"","_agent_featured":"","_agent_job":"","_agent_email":"gemma-mahan@6vv.johana.top","_agent_website":"","_agent_phone":"","_agent_fax":""},"_agent_socials":{"_agent_socials":""},"_agent_location":{"_agent_address":"","_agent_map_location":""}},"_links":{"self":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent\/4092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent"}],"about":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/types\/agent"}],"replies":[{"embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/comments?post=4092"}],"wp:attachment":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/media?parent=4092"}],"wp:term":[{"taxonomy":"agent_location","embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent_location?post=4092"},{"taxonomy":"agent_category","embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent_category?post=4092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}