{"id":4026,"date":"2025-06-20T09:20:21","date_gmt":"2025-06-20T09:20:21","guid":{"rendered":"https:\/\/testedwebsite.us\/realestatee\/agent\/smart-robot4904\/"},"modified":"2025-06-20T09:20:21","modified_gmt":"2025-06-20T09:20:21","slug":"smart-robot4904","status":"publish","type":"agent","link":"https:\/\/testedwebsite.us\/realestatee\/agent\/smart-robot4904\/","title":{"rendered":"smart robot4904"},"content":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","agent_location":[],"agent_category":[],"class_list":["post-4026","agent","type-agent","status-publish","hentry"],"cmb2":{"_agent_contact_details":{"_agent_attached_user":"","_agent_featured":"","_agent_job":"","_agent_email":"marilou.algeranoff84@ch1.johnnie.top","_agent_website":"","_agent_phone":"","_agent_fax":""},"_agent_socials":{"_agent_socials":""},"_agent_location":{"_agent_address":"","_agent_map_location":""}},"_links":{"self":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent\/4026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent"}],"about":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/types\/agent"}],"replies":[{"embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/comments?post=4026"}],"wp:attachment":[{"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/media?parent=4026"}],"wp:term":[{"taxonomy":"agent_location","embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent_location?post=4026"},{"taxonomy":"agent_category","embeddable":true,"href":"https:\/\/testedwebsite.us\/realestatee\/wp-json\/wp\/v2\/agent_category?post=4026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}